{"id":338,"date":"2017-07-26T19:21:58","date_gmt":"2017-07-26T19:21:58","guid":{"rendered":"https:\/\/peterklemperer.com\/blog\/wp-content\/uploads\/2017\/06\/IMG_20170703_122311191_TOP-1.jpg"},"modified":"2017-07-26T19:21:58","modified_gmt":"2017-07-26T19:21:58","slug":"img_20170703_122311191_top-2","status":"inherit","type":"attachment","link":"https:\/\/peterklemperer.com\/blog\/2017\/06\/02\/textile-modeling-and-implementation\/img_20170703_122311191_top-2\/","title":{"rendered":"IMG_20170703_122311191_TOP"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-338","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a1VqWo-5s","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/peterklemperer.com\/blog\/wp-content\/uploads\/2017\/06\/IMG_20170703_122311191_TOP-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/peterklemperer.com\/blog\/wp-content\/uploads\/2017\/06\/IMG_20170703_122311191_TOP-1.jpg\" class=\"attachment-medium size-medium\" alt=\"\" data-attachment-id=\"338\" data-permalink=\"https:\/\/peterklemperer.com\/blog\/2017\/06\/02\/textile-modeling-and-implementation\/img_20170703_122311191_top-2\/\" data-orig-file=\"https:\/\/peterklemperer.com\/blog\/wp-content\/uploads\/2017\/06\/IMG_20170703_122311191_TOP-1.jpg\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image-title=\"IMG_20170703_122311191_TOP\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/peterklemperer.com\/blog\/wp-content\/uploads\/2017\/06\/IMG_20170703_122311191_TOP-1.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{},"post":287,"source_url":"https:\/\/peterklemperer.com\/blog\/wp-content\/uploads\/2017\/06\/IMG_20170703_122311191_TOP-1.jpg","filename":"IMG_20170703_122311191_TOP-1.jpg","filesize":1091625,"_links":{"self":[{"href":"https:\/\/peterklemperer.com\/blog\/wp-json\/wp\/v2\/media\/338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peterklemperer.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/peterklemperer.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/peterklemperer.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/peterklemperer.com\/blog\/wp-json\/wp\/v2\/comments?post=338"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":287,"href":"https:\/\/peterklemperer.com\/blog\/wp-json\/wp\/v2\/posts\/287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}